{"id":15381,"date":"2018-07-22T12:49:46","date_gmt":"2018-07-22T16:49:46","guid":{"rendered":"https:\/\/serescodehumidifiers.com\/?page_id=15381"},"modified":"2024-11-22T14:24:08","modified_gmt":"2024-11-22T19:24:08","slug":"serie-ne-200","status":"publish","type":"page","link":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/","title":{"rendered":"S\u00e9rie NE 200"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15381\" class=\"elementor elementor-15381 elementor-4821\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04d6be3 e-flex e-con-boxed e-con e-parent\" data-id=\"04d6be3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25a1809 elementor-widget elementor-widget-breadcrumbs\" data-id=\"25a1809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/serescodehumidifiers.com\/fr\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43f43525 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43f43525\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cb49f9b\" data-id=\"4cb49f9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edfca54 elementor-widget elementor-widget-text-editor\" data-id=\"edfca54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"three\">\u00a0<\/div><h1>Notre r\u00eave \u00e9tait de cr\u00e9er le d\u00e9shumidificateur \u00e0 deux compresseurs le plus flexible et le plus facile \u00e0 installer, dans le plus petit espace possible.<\/h1><h6>NOUVELLE S\u00c9RIE NE<\/h6><h2>Imaginez<\/h2><div class=\"blue-bg\"><ul><li>Un d\u00e9shumidificateur con\u00e7u sp\u00e9cifiquement pour relever tous les d\u00e9fis du march\u00e9 de la r\u00e9novation et du remplacement.<\/li><li>La tranquillit\u00e9 d&rsquo;esprit d&rsquo;un syst\u00e8me compact \u00e0 deux compresseurs avec des circuits redondants et totalement ind\u00e9pendants contr\u00f4l\u00e9s par un seul cerveau sophistiqu\u00e9.<\/li><li>Deux compresseurs pour des performances modulables et une efficacit\u00e9 \u00e9nerg\u00e9tique optimale dans toutes les conditions.<\/li><li>L&rsquo;installation est simplifi\u00e9e par la division de l&rsquo;unit\u00e9 en deux, sans n\u00e9cessiter de travaux de r\u00e9frig\u00e9ration suppl\u00e9mentaires sur le terrain.<\/li><li>Des unit\u00e9s capables d&rsquo;\u00e9liminer jusqu&rsquo;\u00e0 80 lb\/h d&rsquo;humidit\u00e9 et de traiter 6 800 CFM d&rsquo;air passent par une porte de 32 pouces, avec une capacit\u00e9 d&rsquo;installation divis\u00e9e ne n\u00e9cessitant rien de plus qu&rsquo;un faisceau de c\u00e2bles pour relier les syst\u00e8mes.<\/li><\/ul><\/div><h1>Voici comment nous avons proc\u00e9d\u00e9.<\/h1><h6>SERESCO<\/h6><h2>Un d\u00e9shumidificateur de remplacement parfait pour les piscines int\u00e9rieures<\/h2><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2022\/02\/ser-200-1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"mb-5 aligncenter wp-image-9731 size-medium\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2022\/02\/ser-200-1-283x300.png\" alt=\"Seresco NE 200 Series\" width=\"283\" height=\"300\" srcset=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2022\/02\/ser-200-1-283x300.png 283w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2022\/02\/ser-200-1.png 656w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/><\/a><p>S\u00e9rie NE 200 de SerescoNotre objectif avec la gamme de d\u00e9shumidificateurs de la s\u00e9rie NE 200 \u00e9tait de r\u00e9soudre les probl\u00e8mes difficiles et co\u00fbteux li\u00e9s \u00e0 la modernisation et au remplacement des d\u00e9shumidificateurs. Ce que nous avons obtenu est du pur g\u00e9nie. Non seulement nous avons doubl\u00e9 la capacit\u00e9 de d\u00e9shumidification dans un espace d\u00e9j\u00e0 r\u00e9duit, mais nous avons cr\u00e9\u00e9 un syst\u00e8me enti\u00e8rement redondant, une capacit\u00e9 d&rsquo;installation divis\u00e9e et de s\u00e9rieuses \u00e9conomies d&rsquo;\u00e9nergie, avec une gestion de la charge \u00e9volutive. Bien s\u00fbr, tout ceci est construit avec la m\u00eame attention exceptionnelle aux d\u00e9tails, aux composants de qualit\u00e9 et aux caract\u00e9ristiques technologiques de nos produits de r\u00e9f\u00e9rence, y compris la technologie WebSentry et notre garantie in\u00e9gal\u00e9e. Pour les installations n\u00e9cessitant une \u00e9limination de l&rsquo;humidit\u00e9 de 45 \u00e0 170 lbs\/h et un traitement de l&rsquo;air de 3 000 \u00e0 16 000 CFM, notre s\u00e9rie NE 200 offre des caract\u00e9ristiques qui battent la concurrence haut la main &#8211; \u00e0 tous les coups !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-eeff09a e-flex e-con-boxed e-con e-parent\" data-id=\"eeff09a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1aeb7e3 elementor-widget elementor-widget-spacer\" data-id=\"1aeb7e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-288e563 e-flex e-con-boxed e-con e-parent\" data-id=\"288e563\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ec98a5 elementor-widget elementor-widget-heading\" data-id=\"9ec98a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous avez des questions ? Contactez nous<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcb50dd e-flex e-con-boxed e-con e-parent\" data-id=\"bcb50dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d1e54d elementor-button-warning elementor-widget elementor-widget-button\" data-id=\"0d1e54d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/serescodehumidifiers.com\/fr\/nous-contacter\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ee06b4 elementor-widget elementor-widget-spacer\" data-id=\"0ee06b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbefa7c elementor-widget elementor-widget-text-editor\" data-id=\"fbefa7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>S\u00c9RIE NE200<\/h6><h2 class=\"mb-5\">Autres informations<\/h2><div id=\"tabs\" class=\"prods\"><ul class=\"clearfix d-flex justify-content-between\"><li><a href=\"#tabs-1\">FAITS MARQUANTS<\/a><\/li><li><a href=\"#tabs-2\">CARACT\u00c9RISTIQUES TECHNIQUES<\/a><\/li><li><a href=\"#tabs-3\">Options<\/a><\/li><li><a href=\"#tabs-4\">CARACT\u00c9RISTIQUES STANDARD<\/a><\/li><li><a href=\"#tabs-5\">t\u00e9l\u00e9chargements<\/a><\/li><\/ul><div id=\"tabs-1\"><ul class=\"products-tabs\"><li>45 \u00e0 170 lb\/h d&rsquo;\u00e9limination de l&rsquo;humidit\u00e9 et 3 000 \u00e0 16 000 CFM de traitement de l&rsquo;air dans l&rsquo;encombrement le plus r\u00e9duit possible<\/li><li>Notre mod\u00e8le 214, qui passe par une porte de 32 pouces, permet d&rsquo;\u00e9liminer jusqu&rsquo;\u00e0 79 lb\/h d&rsquo;humidit\u00e9 et 6 800 PCM de traitement de l&rsquo;air.<\/li><li>Syst\u00e8me enti\u00e8rement modulaire<ul><li>2 compresseurs, 2 ventilateurs de soufflage, 2 armoires<\/li><li>un seul ensemble<\/li><\/ul><\/li><li>Peut \u00eatre facilement divis\u00e9 sur le chantier pour \u00eatre install\u00e9 dans des b\u00e2timents existants<ul><li>seulement un faisceau de c\u00e2bles \u00e0 connecter, aucune tuyauterie de r\u00e9frig\u00e9ration n&rsquo;est affect\u00e9e<\/li><\/ul><\/li><li>Acc\u00e8s \u00e0 l&rsquo;entretien sur les deux c\u00f4t\u00e9s pour les installations \u00e9troites<\/li><li>Alimentation \u00e9lectrique monophas\u00e9e disponible jusqu&rsquo;\u00e0 un syst\u00e8me de 12 tonnes<\/li><li>Configurations horizontales et verticales disponibles<\/li><li>Ouvertures d&rsquo;alimentation en air flexibles &#8211; possibilit\u00e9 d&rsquo;ouvertures multiples<\/li><li>Ventilateurs de plenum \u00e0 entra\u00eenement direct inclin\u00e9s vers l&rsquo;arri\u00e8re pour l&rsquo;air d&rsquo;alimentation<ul><li>Pressions statiques plus \u00e9lev\u00e9es, fonctionnement plus silencieux, meilleure efficacit\u00e9 \u00e9nerg\u00e9tique<\/li><li>Moteurs ECM ou entra\u00eenements \u00e0 fr\u00e9quence variable disponibles<\/li><\/ul><\/li><li>Le vestibule m\u00e9canique en dehors du flux d&rsquo;air prot\u00e8ge les composants et facilite l&rsquo;entretien.<\/li><li>Protection sup\u00e9rieure du compresseur<\/li><li>R\u00e9sistance \u00e0 la corrosion de premi\u00e8re qualit\u00e9<\/li><li>Syst\u00e8me de commande CommandCenter<ul><li>Panneau de commande \u00e0 \u00e9cran tactile sophistiqu\u00e9<\/li><li>Le panneau de commande \u00e0 distance peut \u00eatre install\u00e9 \u00e0 une distance maximale de 1 000 pieds.<\/li><li>Les transducteurs de pression de r\u00e9frig\u00e9ration peuvent \u00eatre surveill\u00e9s via WebSentry<\/li><li>unique \u00e0 Seresco<\/li><li>Registre de d\u00e9rivation de l&rsquo;\u00e9vaporateur motoris\u00e9 pour une charge appropri\u00e9e de l&rsquo;\u00e9vaporateur et une efficacit\u00e9 maximale.<\/li><\/ul><\/li><li>Surveillance et contr\u00f4le par Internet WebSentry en tant que caract\u00e9ristique standard<\/li><li>Peut \u00eatre \u00e9quip\u00e9 d&rsquo;un chauffage d&rsquo;air auxiliaire et d&rsquo;une vari\u00e9t\u00e9 d&rsquo;options de ventilation, y compris l&rsquo;air conditionn\u00e9.<\/li><\/ul><\/div><div id=\"tabs-2\"><ul class=\"products-tabs\"><li><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2020\/08\/NE-208-Horizontal-07-2013_Fixed2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">NE-208<\/a><\/li><li><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2020\/08\/NE-210-Horizontal-07-2013_Fixed2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">NE-210<\/a><\/li><li><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2020\/08\/NE-212-Horizontal-07-2013_Fixed2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">NE-212<\/a><\/li><li><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2020\/08\/NE-214-Horizontal-07-2013_Fixed2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">NE-214<\/a><\/li><li><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2023\/01\/ne-220-07-2013.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">NE-220<\/a><\/li><li><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2023\/01\/ne-224-07-2013.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">NE-224<\/a><\/li><li><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2023\/01\/ne-232-07-2013.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">NE-232<\/a><\/li><\/ul><\/div><div id=\"tabs-3\"><ul class=\"products-tabs\"><li>Chauffage de l&rsquo;eau de piscine<\/li><li>Echappement avec r\u00e9cup\u00e9ration de chaleur<\/li><li>Mode purge avec \u00e9conomiseur<\/li><li>Climatisation &#8211; refroidie \u00e0 l&rsquo;air ou \u00e0 l&rsquo;eau, split ou packag\u00e9e<\/li><li>Chauffage de l&rsquo;air auxiliaire<\/li><li>Volet motoris\u00e9 de mise en marche et d&rsquo;arr\u00eat de l&rsquo;air ext\u00e9rieur reli\u00e9 \u00e0 une horloge int\u00e9gr\u00e9e de 7 jours<\/li><li>Ventilation de l&rsquo;air ext\u00e9rieur int\u00e9gr\u00e9e, avec filtre et registre \u00e0 r\u00e9glage manuel<\/li><\/ul><\/div><div id=\"tabs-4\"><ul class=\"products-tabs\"><li>Surveillance et contr\u00f4le par Internet WebSentry<ul><li>Mise en service en usine et assistance par Internet<\/li><li>Surveillance des performances de Seresco Sentinel 24 heures sur 24 et 7 jours sur 7<\/li><li>Alertes de maintenance pr\u00e9ventive par courrier \u00e9lectronique<\/li><li>Avertissements de probl\u00e8mes par courrier \u00e9lectronique<\/li><li>Acc\u00e8s et contr\u00f4le par navigateur<\/li><li>Acc\u00e8s et contr\u00f4le par t\u00e9l\u00e9phone intelligent<\/li><\/ul><\/li><li>Garantie in\u00e9gal\u00e9e d&rsquo;un an sur la main d&rsquo;\u0153uvre avec la connexion WebSentry<\/li><li>Garantie de 2 ans sur les pi\u00e8ces<\/li><li>Syst\u00e8me de contr\u00f4le CommandCenter avec interface \u00e0 \u00e9cran tactile en option<ul><li>Le contr\u00f4leur le plus sophistiqu\u00e9 et le plus puissant de l&rsquo;industrie<\/li><li>Connectivit\u00e9 BACnet, LON et Modbus int\u00e9gr\u00e9e<\/li><\/ul><\/li><li>Vestibule de service Flux d&rsquo;air ext\u00e9rieur &#8211; sur toutes les unit\u00e9s<ul><li>Composants critiques en dehors du flux d&rsquo;air chlor\u00e9<\/li><li>Efficacit\u00e9 maximale de l&rsquo;AC, pas de gain de chaleur des composants chauds<\/li><li>Facilit\u00e9 d&rsquo;entretien, m\u00eame lorsque l&rsquo;unit\u00e9 est en fonctionnement<\/li><\/ul><\/li><li>Ventilateurs \u00e0 entra\u00eenement direct, plenum \u00e0 ailettes inclin\u00e9 vers l&rsquo;arri\u00e8re<ul><li>Silencieux, puissant, efficace, fiable, \u00e9conome en \u00e9nergie<\/li><li>Pressions statiques plus \u00e9lev\u00e9es<\/li><li>Fonctionnement plus silencieux et meilleure efficacit\u00e9 \u00e9nerg\u00e9tique<\/li><li>Permet l&rsquo;installation en usine d&rsquo;un chauffage d&rsquo;air auxiliaire<\/li><li>Offre une flexibilit\u00e9 maximale pour les options de gaines de soufflage d&rsquo;air<\/li><li>Pas de courroies \u00e0 ajuster, \u00e0 user ou \u00e0 remplacer<\/li><\/ul><\/li><li>Serpentins enti\u00e8rement tremp\u00e9s pour une protection \u00e0 100 % contre la corrosion &#8211; pas seulement les ailettes !<\/li><li>Protection extraordinaire du compresseur<ul><li>Transducteurs de pression frigorifique \u00e0 l&rsquo;aspiration et au refoulement &#8211; uniques \u00e0 Seresco<\/li><li>Surveillance 24\/7 des pressions critiques d&rsquo;aspiration et de refoulement<\/li><li>pompe \u00e0 vide, chauffage du carter, contr\u00f4le de la tension<\/li><li>accumulateur d&rsquo;aspiration, s\u00e9parateur d&rsquo;huile, surveillance de l&rsquo;huile<\/li><\/ul><\/li><li>Voyants sur les r\u00e9servoirs pour faciliter la charge des syst\u00e8mes split sur le terrain<\/li><li>Syst\u00e8mes \u00e0 compresseurs multiples pour un contr\u00f4le \u00e9chelonn\u00e9<\/li><li>Ouvertures flexibles pour l&rsquo;alimentation et le retour d&rsquo;air &#8211; possibilit\u00e9 d&rsquo;ouvertures multiples<\/li><li>Le vestibule m\u00e9canique situ\u00e9 en dehors du flux d&rsquo;air facilite l&rsquo;entretien.<\/li><li>Configurations en miroir disponibles pour tous les mod\u00e8les afin de s&rsquo;adapter aux exigences des gaines.<\/li><li>Les meilleures armoires de l&rsquo;industrie<\/li><li>Registre de d\u00e9rivation de l&rsquo;\u00e9vaporateur motoris\u00e9 pour une charge correcte de l&rsquo;\u00e9vaporateur et une efficacit\u00e9 maximale<\/li><li>Filtres pliss\u00e9s de 2 pouces en standard<\/li><\/ul><\/div><div id=\"tabs-5\"><div class=\"grid-container\"><div class=\"grid-25\"><a class=\"real\" href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-ne200-series-dehumidifier-brochure-fr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/01\/Seresco-NE200-Series-Dehumidifier-Brochure-1.jpg\" alt=\"Seresco NE 200 Dehumidifier brochure\" width=\"101\" height=\"131\" \/><\/a><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-ne200-series-dehumidifier-brochure-fr.pdf\"><strong>Seresco<\/strong><br \/>S\u00e9rie NE 200<\/a><\/p><\/div><div class=\"grid-25\"><p><a class=\"real\" href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-dehumidifiers-contractor-brochurefr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/01\/Seresco-Dehumidifiers-Contractor-Brochure-Cover-thumb.png\" alt=\"seresco dehumidifier brochure for contractors\" width=\"100\" height=\"130\" \/><\/a><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-dehumidifiers-contractor-brochurefr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Seresco<\/strong><br \/>Contractors<\/a><\/p><\/div><div class=\"grid-25\"><p><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15954\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-232x300.jpg\" alt=\"\" width=\"100\" height=\"129\" srcset=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-232x300.jpg 232w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-791x1024.jpg 791w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-768x994.jpg 768w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-1187x1536.jpg 1187w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-1583x2048.jpg 1583w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-scaled.jpg 1978w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench.pdf\"><strong>Seresco<\/strong><br \/>WebSentry<\/a><\/p><\/div><\/div><div class=\"grid-container\"><div class=\"grid-25\"><p><a class=\"real\" href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-condensers-and-coolers-brochurefrench.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/01\/Seresco-Condensers-and-Coolers-Brochure-thumb.jpg\" alt=\"Seresco NC and NG Series brochure\" width=\"101\" height=\"131\" \/><\/a><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-condensers-and-coolers-brochurefrench.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Seresco<\/strong><br \/><\/a><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-condensers-and-coolers-brochurefrench.pdf\">S\u00e9rie <\/a><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-condensers-and-coolers-brochurefrench.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">NC<br \/><br \/><\/a><\/p><\/div><div class=\"grid-25\"><p><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16117\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-232x300.jpg\" alt=\"\" width=\"100\" height=\"129\" srcset=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-232x300.jpg 232w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-791x1024.jpg 791w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-768x994.jpg 768w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-1187x1536.jpg 1187w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-1583x2048.jpg 1583w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-scaled.jpg 1978w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a><p><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french.pdf\"><strong>Seresco<\/strong><br \/>Natatorium Guide de Conception<\/a><\/p><\/div><div class=\"grid-25\">\u00a0<\/div><div class=\"grid-25\">\u00a0<\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend pgfw-icon-display pgfw-icon-display--default\" style=\"--pgfw-icon-justify:center;\"><a href=\"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15381\/?action=genpdf&#038;id=15381\" class=\"pgfw-single-pdf-download-button pgfw-single-pdf-download-button--default pgfw-single-pdf-download-button--icon-only\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"--pgfw-icon-width:25px;--pgfw-icon-height:45px;\" aria-label=\"Download PDF\"><span class=\"pgfw-single-pdf-download-button__media\" aria-hidden=\"true\"><img src=\"https:\/\/serescodehumidifiers.com\/wp-content\/plugins\/pdf-generator-for-wp\/admin\/src\/images\/PDF_Tray.svg\" alt=\"\" decoding=\"async\"><\/span><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Notre r\u00eave \u00e9tait de cr\u00e9er le d\u00e9shumidificateur \u00e0 deux compresseurs le plus flexible et le plus facile \u00e0 installer, dans le plus petit espace possible. NOUVELLE S\u00c9RIE NE Imaginez Un d\u00e9shumidificateur con\u00e7u sp\u00e9cifiquement pour relever tous les d\u00e9fis du march\u00e9 de la r\u00e9novation et du remplacement. La tranquillit\u00e9 d&rsquo;esprit d&rsquo;un syst\u00e8me compact \u00e0 deux &#8230; <a title=\"S\u00e9rie NE 200\" class=\"read-more\" href=\"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/\" aria-label=\"En savoir plus sur S\u00e9rie NE 200\">Lire la suite<\/a><\/p>\n","protected":false},"author":6,"featured_media":14194,"parent":15356,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"generate_page_header":"","footnotes":""},"class_list":["post-15381","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9rie NE 200 - Seresco Dehumidifiers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9rie NE 200 - Seresco Dehumidifiers\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Notre r\u00eave \u00e9tait de cr\u00e9er le d\u00e9shumidificateur \u00e0 deux compresseurs le plus flexible et le plus facile \u00e0 installer, dans le plus petit espace possible. NOUVELLE S\u00c9RIE NE Imaginez Un d\u00e9shumidificateur con\u00e7u sp\u00e9cifiquement pour relever tous les d\u00e9fis du march\u00e9 de la r\u00e9novation et du remplacement. La tranquillit\u00e9 d&rsquo;esprit d&rsquo;un syst\u00e8me compact \u00e0 deux ... Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/\" \/>\n<meta property=\"og:site_name\" content=\"Seresco Dehumidifiers\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-22T19:24:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/07\/ne-2000-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-200\\\/\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-200\\\/\",\"name\":\"S\u00e9rie NE 200 - Seresco Dehumidifiers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-200\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-200\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ne-2000-min.jpg\",\"datePublished\":\"2018-07-22T16:49:46+00:00\",\"dateModified\":\"2024-11-22T19:24:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-200\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-200\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-200\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ne-2000-min.jpg\",\"contentUrl\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ne-2000-min.jpg\",\"width\":1920,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-200\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9rie NE 200\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/\",\"name\":\"Seresco Dehumidifiers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#organization\",\"name\":\"Seresco Dehumidifiers\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/fichier-1seresco.svg\",\"contentUrl\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/fichier-1seresco.svg\",\"caption\":\"Seresco Dehumidifiers\"},\"image\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9rie NE 200 - Seresco Dehumidifiers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9rie NE 200 - Seresco Dehumidifiers","og_description":"\u00a0 Notre r\u00eave \u00e9tait de cr\u00e9er le d\u00e9shumidificateur \u00e0 deux compresseurs le plus flexible et le plus facile \u00e0 installer, dans le plus petit espace possible. NOUVELLE S\u00c9RIE NE Imaginez Un d\u00e9shumidificateur con\u00e7u sp\u00e9cifiquement pour relever tous les d\u00e9fis du march\u00e9 de la r\u00e9novation et du remplacement. La tranquillit\u00e9 d&rsquo;esprit d&rsquo;un syst\u00e8me compact \u00e0 deux ... Lire la suite","og_url":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/","og_site_name":"Seresco Dehumidifiers","article_modified_time":"2024-11-22T19:24:08+00:00","og_image":[{"width":1920,"height":701,"url":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/07\/ne-2000-min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/","url":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/","name":"S\u00e9rie NE 200 - Seresco Dehumidifiers","isPartOf":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/#primaryimage"},"image":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/#primaryimage"},"thumbnailUrl":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/07\/ne-2000-min.jpg","datePublished":"2018-07-22T16:49:46+00:00","dateModified":"2024-11-22T19:24:08+00:00","breadcrumb":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/#primaryimage","url":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/07\/ne-2000-min.jpg","contentUrl":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/07\/ne-2000-min.jpg","width":1920,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-200\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serescodehumidifiers.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/serescodehumidifiers.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"S\u00e9rie NE 200"}]},{"@type":"WebSite","@id":"https:\/\/serescodehumidifiers.com\/fr\/#website","url":"https:\/\/serescodehumidifiers.com\/fr\/","name":"Seresco Dehumidifiers","description":"","publisher":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serescodehumidifiers.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/serescodehumidifiers.com\/fr\/#organization","name":"Seresco Dehumidifiers","url":"https:\/\/serescodehumidifiers.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/serescodehumidifiers.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/08\/fichier-1seresco.svg","contentUrl":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/08\/fichier-1seresco.svg","caption":"Seresco Dehumidifiers"},"image":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/comments?post=15381"}],"version-history":[{"count":4,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15381\/revisions"}],"predecessor-version":[{"id":16634,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15381\/revisions\/16634"}],"up":[{"embeddable":true,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/media\/14194"}],"wp:attachment":[{"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/media?parent=15381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}