{"id":15408,"date":"2024-08-05T13:10:46","date_gmt":"2024-08-05T17:10:46","guid":{"rendered":"https:\/\/serescodehumidifiers.com\/?page_id=15408"},"modified":"2026-07-28T10:04:19","modified_gmt":"2026-07-28T14:04:19","slug":"serie-ne-compact-avec-option-bas-point-de-rosee","status":"publish","type":"page","link":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/","title":{"rendered":"S\u00e9rie NE Compact avec option bas point de ros\u00e9e"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15408\" class=\"elementor elementor-15408 elementor-15141\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af4e038 e-flex e-con-boxed e-con e-parent\" data-id=\"af4e038\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cafd362 elementor-widget elementor-widget-breadcrumbs\" data-id=\"cafd362\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/serescodehumidifiers.com\/fr\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d6822d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d6822d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b4ab5a4\" data-id=\"7b4ab5a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13899411 elementor-widget elementor-widget-text-editor\" data-id=\"13899411\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1><span style=\"color: inherit; font-size: 0.8rem; font-style: inherit; font-weight: 600; letter-spacing: 0.7em; text-transform: uppercase;\">SERESCO<\/span><\/h1><h2>S\u00e9rie NE Compact avec option bas point de ros\u00e9e<\/h2><p><strong>Fiabilit\u00e9 in\u00e9gal\u00e9e dans divers environnements<\/strong><\/p><p>Les syst\u00e8mes CVC \u00e0 faible point de ros\u00e9e de Seresco sont sp\u00e9cialement con\u00e7us pour r\u00e9pondre aux besoins extr\u00eames de d\u00e9shumidification des centres de traitement des eaux, des installations d&rsquo;archivage ou de tout autre environnement o\u00f9 la d\u00e9shumidification est requise \u00e0 des points de ros\u00e9e inf\u00e9rieurs.<\/p><p>Notre technologie de compresseur \u00e0 deux \u00e9tages offre non seulement une faible consommation d&rsquo;\u00e9nergie, mais emp\u00eache \u00e9galement le gel du serpentin d&rsquo;\u00e9vaporation, ce qui permet de climatiser et de d\u00e9shumidifier avec des points de ros\u00e9e de l&rsquo;air entrant aussi bas que 40\u00b0F. Gr\u00e2ce \u00e0 la surveillance Internet 24\/7 via WebSentry\u00ae, vous pouvez garantir des performances optimales et des alertes imm\u00e9diates, pour une tranquillit\u00e9 d&rsquo;esprit et une efficacit\u00e9 op\u00e9rationnelle accrues.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d23c826\" data-id=\"d23c826\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae48796 elementor-widget elementor-widget-image\" data-id=\"ae48796\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"656\" height=\"696\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/08\/ser-200-2024.png\" class=\"attachment-large size-large wp-image-15250\" alt=\"\" srcset=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/08\/ser-200-2024.png 656w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/08\/ser-200-2024-283x300.png 283w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6d0a760 e-flex e-con-boxed e-con e-parent\" data-id=\"6d0a760\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abb813c elementor-widget elementor-widget-spacer\" data-id=\"abb813c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf7d08 elementor-widget elementor-widget-text-editor\" data-id=\"7bf7d08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>\u00a0<\/h6><div id=\"tabs\" class=\"prods\"><ul class=\"clearfix d-flex justify-content-between\"><li><a href=\"#tabs-1\">FAITS MARQUANTS<\/a><\/li><li><a href=\"#tabs-3\">CANDIDATURES<\/a><\/li><li><a href=\"#tabs-4\">CARACT\u00c9RISTIQUES STANDARD<\/a><\/li><li><a href=\"#tabs-5\">t\u00e9l\u00e9chargements<\/a><\/li><\/ul><div id=\"tabs-1\"><ul class=\"products-tabs\"><li>Disponible sur les s\u00e9ries NE Compact de 2 \u00e0 8 tonnes existantes, y compris les unit\u00e9s superpos\u00e9es.<\/li><li>Compresseurs \u00e0 2 \u00e9tages pour un contr\u00f4le pr\u00e9cis de l&rsquo;environnement<\/li><li>Valves d&rsquo;expansion \u00e9lectroniques (EEV) pour un d\u00e9bit de r\u00e9frig\u00e9rant pr\u00e9cis<\/li><li>Capacit\u00e9 de climatisation<\/li><li>Technologie de d\u00e9shumidification silencieuse et ultra-efficace dans un encombrement r\u00e9duit<\/li><li>Les multiples options de raccordement des conduits d&rsquo;air offrent une grande souplesse pour les r\u00e9novations ou les nouvelles constructions.<\/li><li>Les composants critiques sont maintenus hors du flux d&rsquo;air.<\/li><li>Surveillance par Internet 24 heures sur 24 et 7 jours sur 7 via WebSentry<\/li><li>Garantie in\u00e9gal\u00e9e d&rsquo;un an sur la main d&rsquo;\u0153uvre avec la connexion WebSentry<\/li><li>Garantie de 2 ans sur les pi\u00e8ces<\/li><\/ul><\/div><div id=\"tabs-3\"><ul class=\"products-tabs\"><li>Centres de traitement des eaux<\/li><li>Archives<\/li><li>Biblioth\u00e8ques<\/li><li>Installations de stockage<\/li><li>Entrep\u00f4ts<\/li><li>Vides sanitaires<\/li><li>Caves<\/li><li>Salles de s\u00e9chage de parachutes<\/li><li>S\u00e9choirs pour tuyaux d&rsquo;incendie<\/li><li>Et plus encore&#8230;<\/li><\/ul><\/div><div id=\"tabs-4\"><ul class=\"products-tabs\"><li>Surveillance et contr\u00f4le par Internet WebSentry<ul><li>Mise en service supervis\u00e9e par l&rsquo;usine et assistance via Internet<\/li><li>Surveillance des performances de Seresco WebSentry 24 heures sur 24, 7 jours sur 7<\/li><li>Avertissements de probl\u00e8mes par courrier \u00e9lectronique<\/li><li>Acc\u00e8s et contr\u00f4le par navigateur<\/li><li>Acc\u00e8s et contr\u00f4le par t\u00e9l\u00e9phone intelligent<\/li><\/ul><\/li><li>Garantie in\u00e9gal\u00e9e d&rsquo;un an sur la main-d&rsquo;\u0153uvre avec la connexion WebSentry<\/li><li>Garantie de 2 ans sur les pi\u00e8ces<\/li><li>Syst\u00e8me de contr\u00f4le CommandCenter avec interface \u00e0 \u00e9cran tactile en option<ul><li>Le contr\u00f4leur le plus sophistiqu\u00e9 et le plus puissant de l&rsquo;industrie<\/li><li>Connectivit\u00e9 BACnet, LON et Modbus int\u00e9gr\u00e9e<\/li><\/ul><\/li><li>Vestibule d&rsquo;entretien \u00e0 l&rsquo;ext\u00e9rieur du flux d&rsquo;air &#8211; sur toutes les unit\u00e9s<ul><li>Composants critiques \u00e0 l&rsquo;ext\u00e9rieur du flux d&rsquo;air chlor\u00e9<\/li><li>Efficacit\u00e9 maximale de l&rsquo;AC, pas de gain de chaleur des composants chauds<\/li><li>Facilit\u00e9 d&rsquo;entretien, m\u00eame lorsque l&rsquo;unit\u00e9 est en fonctionnement<\/li><\/ul><\/li><li>Ventilateurs \u00e0 entra\u00eenement direct, plenum \u00e0 ailettes inclin\u00e9 vers l&rsquo;arri\u00e8re<ul><li>Silencieux, puissant, efficace, fiable, \u00e9conome en \u00e9nergie<\/li><li>Pressions statiques plus \u00e9lev\u00e9es<\/li><li>Fonctionnement plus silencieux et meilleure efficacit\u00e9 \u00e9nerg\u00e9tique<\/li><li>Permet l&rsquo;installation en usine d&rsquo;un chauffage d&rsquo;air auxiliaire<\/li><li>Offre une flexibilit\u00e9 maximale pour les options de gaines de soufflage d&rsquo;air<\/li><li>Pas de courroies \u00e0 ajuster, \u00e0 user ou \u00e0 remplacer<\/li><\/ul><\/li><li>Serpentins enti\u00e8rement tremp\u00e9s pour une protection \u00e0 100 % contre la corrosion &#8211; pas seulement les ailettes !<\/li><li>Protection extraordinaire du compresseur<ul><li>Transducteurs de pression frigorifique \u00e0 l&rsquo;aspiration et au refoulement &#8211; uniques \u00e0 Seresco<\/li><li>Surveillance 24\/7 des pressions critiques d&rsquo;aspiration et de refoulement<\/li><li>arr\u00eat de la pompe, chauffage du carter, contr\u00f4le de la tension<\/li><li>accumulateur d&rsquo;aspiration, s\u00e9parateur d&rsquo;huile, surveillance de l&rsquo;huile<\/li><\/ul><\/li><li>Voyants sur les r\u00e9cepteurs pour faciliter le chargement des syst\u00e8mes split sur le terrain<\/li><li>Ouvertures de soufflage et de reprise d&rsquo;air flexibles &#8211; possibilit\u00e9 d&rsquo;ouvertures multiples<\/li><li>Le vestibule m\u00e9canique situ\u00e9 \u00e0 l&rsquo;ext\u00e9rieur du flux d&rsquo;air facilite l&rsquo;entretien.<\/li><li>Configurations en miroir disponibles pour tous les mod\u00e8les afin de s&rsquo;adapter aux exigences des conduits.<\/li><li>Les meilleures armoires de l&rsquo;industrie<\/li><li>Climatiseurs ext\u00e9rieurs monoblocs et biblocs disponibles, refroidis \u00e0 l&rsquo;air ou \u00e0 sec<\/li><li>Conception de base compatible avec le toit ou la dalle<\/li><li>Registre de d\u00e9rivation de l&rsquo;\u00e9vaporateur motoris\u00e9 pour une charge correcte de l&rsquo;\u00e9vaporateur et une efficacit\u00e9 maximale<\/li><li>Filtres pliss\u00e9s de 2 pouces en standard<\/li><\/ul><\/div><div id=\"tabs-5\"><div class=\"grid-container\"><div class=\"grid-25\"><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench.pdf\"><img decoding=\"async\" class=\"alignnone wp-image-15954\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-232x300.jpg\" alt=\"\" width=\"100\" height=\"129\" srcset=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-232x300.jpg 232w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-791x1024.jpg 791w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-768x994.jpg 768w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-1187x1536.jpg 1187w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-1583x2048.jpg 1583w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench-page-1-scaled.jpg 1978w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a><br \/><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/serescowebsentrybrochurefrench.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>WebSentry <\/strong><\/a><\/p><\/div><div class=\"grid-25\"><p><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr.pdf\"><img decoding=\"async\" class=\"alignnone wp-image-15968\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr-page-1-232x300.jpg\" alt=\"\" width=\"100\" height=\"129\" srcset=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr-page-1-232x300.jpg 232w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr-page-1-792x1024.jpg 792w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr-page-1-768x994.jpg 768w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr-page-1-1187x1536.jpg 1187w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr-page-1-1583x2048.jpg 1583w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr-page-1.jpg 1658w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a><br \/><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/aar-new-ne-brochure2024-fr.pdf\"><strong>Seresco NE<\/strong><\/a><\/p><\/div><\/div><div class=\"grid-container\"><div class=\"grid-25\"><p><a class=\"real\" href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-low-dewpoint-system-cut-sheet-2024dfr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/08\/seresco-low-dewpoint-systems-thumbnail2.png\" alt=\"Low Dew Point Option Brochure\" width=\"101\" height=\"131\" \/><\/a><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-low-dewpoint-system-cut-sheet-2024dfr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Seresco<\/strong><br \/>S\u00e9rie NE Compact avec option bas point de ros\u00e9e<\/a><\/p><\/div><div class=\"grid-25\"><p><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french.pdf \"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16117\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-232x300.jpg\" alt=\"\" width=\"100\" height=\"129\" srcset=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-232x300.jpg 232w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-791x1024.jpg 791w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-768x994.jpg 768w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-1187x1536.jpg 1187w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-1583x2048.jpg 1583w, https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french-scaled.jpg 1978w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-pool-guide-french.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Seresco<\/strong><br \/>Natatorium Guide de Conception<\/a><\/p><\/div><div class=\"grid-25\"><p><a class=\"real\" href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-dehumidifiers-contractor-brochurefr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2018\/01\/Seresco-Dehumidifiers-Contractor-Brochure-Cover-thumb.png\" alt=\"Seresco dehumidifier brochure for contractors\" width=\"100\" height=\"130\" \/><\/a><p><a href=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/11\/seresco-dehumidifiers-contractor-brochurefr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Seresco<\/strong><br \/>Contractants<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9322f5a e-flex e-con-boxed e-con e-parent\" data-id=\"9322f5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-539ba57 elementor-widget elementor-widget-heading\" data-id=\"539ba57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous avez des questions ? Contactez nous<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0da6b7e elementor-button-warning elementor-widget elementor-widget-button\" data-id=\"0da6b7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/serescodehumidifiers.com\/fr\/nous-contacter\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15408\/?action=genpdf&amp;id=15408\" class=\"pgfw-single-pdf-download-button\" ><img src=\"https:\/\/serescodehumidifiers.com\/wp-content\/plugins\/pdf-generator-for-wp\/admin\/src\/images\/PDF_Tray.svg\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>SERESCO S\u00e9rie NE Compact avec option bas point de ros\u00e9e Fiabilit\u00e9 in\u00e9gal\u00e9e dans divers environnements Les syst\u00e8mes CVC \u00e0 faible point de ros\u00e9e de Seresco sont sp\u00e9cialement con\u00e7us pour r\u00e9pondre aux besoins extr\u00eames de d\u00e9shumidification des centres de traitement des eaux, des installations d&rsquo;archivage ou de tout autre environnement o\u00f9 la d\u00e9shumidification est requise \u00e0 &#8230; <a title=\"S\u00e9rie NE Compact avec option bas point de ros\u00e9e\" class=\"read-more\" href=\"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/\" aria-label=\"En savoir plus sur S\u00e9rie NE Compact avec option bas point de ros\u00e9e\">Lire la suite<\/a><\/p>\n","protected":false},"author":6,"featured_media":15151,"parent":15356,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"generate_page_header":"","footnotes":""},"class_list":["post-15408","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9rie NE Compact avec option bas point de ros\u00e9e - Seresco Dehumidifiers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9rie NE Compact avec option bas point de ros\u00e9e - Seresco Dehumidifiers\" \/>\n<meta property=\"og:description\" content=\"SERESCO S\u00e9rie NE Compact avec option bas point de ros\u00e9e Fiabilit\u00e9 in\u00e9gal\u00e9e dans divers environnements Les syst\u00e8mes CVC \u00e0 faible point de ros\u00e9e de Seresco sont sp\u00e9cialement con\u00e7us pour r\u00e9pondre aux besoins extr\u00eames de d\u00e9shumidification des centres de traitement des eaux, des installations d&rsquo;archivage ou de tout autre environnement o\u00f9 la d\u00e9shumidification est requise \u00e0 ... Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/\" \/>\n<meta property=\"og:site_name\" content=\"Seresco Dehumidifiers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T14:04:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/07\/water-treatment-seresco-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-compact-avec-option-bas-point-de-rosee\\\/\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-compact-avec-option-bas-point-de-rosee\\\/\",\"name\":\"S\u00e9rie NE Compact avec option bas point de ros\u00e9e - Seresco Dehumidifiers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-compact-avec-option-bas-point-de-rosee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-compact-avec-option-bas-point-de-rosee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/water-treatment-seresco.png\",\"datePublished\":\"2024-08-05T17:10:46+00:00\",\"dateModified\":\"2026-07-28T14:04:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-compact-avec-option-bas-point-de-rosee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-compact-avec-option-bas-point-de-rosee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-compact-avec-option-bas-point-de-rosee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/water-treatment-seresco.png\",\"contentUrl\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/water-treatment-seresco.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/serie-ne-compact-avec-option-bas-point-de-rosee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9rie NE Compact avec option bas point de ros\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/\",\"name\":\"Seresco Dehumidifiers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#organization\",\"name\":\"Seresco Dehumidifiers\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/fichier-1seresco.svg\",\"contentUrl\":\"https:\\\/\\\/serescodehumidifiers.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/fichier-1seresco.svg\",\"caption\":\"Seresco Dehumidifiers\"},\"image\":{\"@id\":\"https:\\\/\\\/serescodehumidifiers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9rie NE Compact avec option bas point de ros\u00e9e - Seresco Dehumidifiers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9rie NE Compact avec option bas point de ros\u00e9e - Seresco Dehumidifiers","og_description":"SERESCO S\u00e9rie NE Compact avec option bas point de ros\u00e9e Fiabilit\u00e9 in\u00e9gal\u00e9e dans divers environnements Les syst\u00e8mes CVC \u00e0 faible point de ros\u00e9e de Seresco sont sp\u00e9cialement con\u00e7us pour r\u00e9pondre aux besoins extr\u00eames de d\u00e9shumidification des centres de traitement des eaux, des installations d&rsquo;archivage ou de tout autre environnement o\u00f9 la d\u00e9shumidification est requise \u00e0 ... Lire la suite","og_url":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/","og_site_name":"Seresco Dehumidifiers","article_modified_time":"2026-07-28T14:04:19+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/07\/water-treatment-seresco-1024x576.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/","url":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/","name":"S\u00e9rie NE Compact avec option bas point de ros\u00e9e - Seresco Dehumidifiers","isPartOf":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/#primaryimage"},"image":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/#primaryimage"},"thumbnailUrl":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/07\/water-treatment-seresco.png","datePublished":"2024-08-05T17:10:46+00:00","dateModified":"2026-07-28T14:04:19+00:00","breadcrumb":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/#primaryimage","url":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/07\/water-treatment-seresco.png","contentUrl":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/07\/water-treatment-seresco.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/serescodehumidifiers.com\/fr\/produits\/serie-ne-compact-avec-option-bas-point-de-rosee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serescodehumidifiers.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/serescodehumidifiers.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"S\u00e9rie NE Compact avec option bas point de ros\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/serescodehumidifiers.com\/fr\/#website","url":"https:\/\/serescodehumidifiers.com\/fr\/","name":"Seresco Dehumidifiers","description":"","publisher":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serescodehumidifiers.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/serescodehumidifiers.com\/fr\/#organization","name":"Seresco Dehumidifiers","url":"https:\/\/serescodehumidifiers.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/serescodehumidifiers.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/08\/fichier-1seresco.svg","contentUrl":"https:\/\/serescodehumidifiers.com\/wp-content\/uploads\/2024\/08\/fichier-1seresco.svg","caption":"Seresco Dehumidifiers"},"image":{"@id":"https:\/\/serescodehumidifiers.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/comments?post=15408"}],"version-history":[{"count":3,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15408\/revisions"}],"predecessor-version":[{"id":17814,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15408\/revisions\/17814"}],"up":[{"embeddable":true,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/pages\/15356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/media\/15151"}],"wp:attachment":[{"href":"https:\/\/serescodehumidifiers.com\/fr\/wp-json\/wp\/v2\/media?parent=15408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}